{"id":7843,"date":"2022-09-09T16:23:58","date_gmt":"2022-09-09T15:23:58","guid":{"rendered":"https:\/\/blog.hotelcontinental.com\/?p=7843"},"modified":"2022-09-09T16:23:58","modified_gmt":"2022-09-09T15:23:58","slug":"hotel-palacete-barcelona-oktoberfest-barcelona","status":"publish","type":"post","link":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/","title":{"rendered":"La Oktoberfest Barcelona vuelve al recinto ferial de Montju\u00efc en 2022"},"content":{"rendered":"<p><\/p>\n<h2><strong>Venga a disfrutar del Festival Oktoberfest Barcelona y qu\u00e9dese con nosotros!\u00a0<\/strong><\/h2>\n<p>Si una visita a la Oktoberfest est\u00e1 en tu lista de deseos, pero las temperaturas de octubre en la fr\u00eda M\u00fanich te siguen retrasando, hay buenas noticias.<\/p>\n<h3>El\u00a0<a href=\"https:\/\/www.oktoberfest-barcelona.es\/\">Oktoberfest Barcelona<\/a>\u00a0vuelve al recinto ferial de Montju\u00efc del 5 de octubre de 2022 al 16 de octubre de 2022. Con temperaturas medias nocturnas superiores a los 10 grados en Barcelona, es el lugar para disfrutar de todas las festividades tradicionales de una aut\u00e9ntica Oktoberfest alemana, sin los abrigos de invierno.<\/h3>\n<p>Incluyendo los cierres de covacha de 2020\/21, este ser\u00e1 el noveno festival anual de Oktoberfest Barcelona, y m\u00e1s grande y mejor que ninguno anterior.<\/p>\n<p>Este a\u00f1o, la enorme carpa del festival estar\u00e1 llena de bares alemanes e internacionales, aut\u00e9nticos puestos de comida callejera b\u00e1vara, personal de servicio con trajes tradicionales b\u00e1varos, y escenarios de entretenimiento y asientos para el p\u00fablico. Y la cosa no acaba ah\u00ed.<\/p>\n<p>Fuera de la carpa habr\u00e1 m\u00e1s bares de cerveza, DJs, puestos de comida alemana, bares de tapas espa\u00f1oles y otros puestos que ofrecer\u00e1n delicias de toda Europa. Tambi\u00e9n hay cinco \u00e1reas de entretenimiento para los ni\u00f1os, y quioscos para comprar recuerdos de la Oktoberfest Barcelona. Lo mejor de todo es que la entrada al festival es gratuita.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7844 alignright\" src=\"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/october-fest-1.jpg\" alt=\"Hotel Continental Barcelona Palacete\" width=\"960\" height=\"640\" srcset=\"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/october-fest-1.jpg 960w, https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/october-fest-1-300x200.jpg 300w, https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/october-fest-1-768x512.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/h2>\n<h2><strong>Reserve con antelaci\u00f3n para evitar decepciones<\/strong><\/h2>\n<p>\u00bfEst\u00e1 pensando en visitar la ciudad durante los 12 d\u00edas, o en hacer una breve escapada para disfrutar de un par de d\u00edas de las festividades? Se recomienda reservar con antelaci\u00f3n tanto el hotel como una mesa gratuita en la carpa. Los hoteles se reservan muy r\u00e1pidamente con visitantes de toda Europa para este evento de primera categor\u00eda: y por razones de seguridad, la entrada a la carpa principal est\u00e1 limitada diariamente.<\/p>\n<p><strong>Un festival que no se puede perder<\/strong><\/p>\n<p>El festival comienza cuando el maestro de ceremonias abre el primer barril de madera y anuncia por la megafon\u00eda a todo el mundo: \u00abEst\u00e1 abierto\u00bb (en alem\u00e1n, por supuesto).<\/p>\n<p>Los festejos comienzan y terminan a diferentes horas en diferentes d\u00edas, por lo que tendr\u00e1 unas cuantas horas que llenar. Qu\u00e9 mejor manera de hacerlo que haciendo un poco de turismo por la hermosa ciudad de Barcelona.<\/p>\n<h2><strong>El mejor hotel para su visita al Oktoberfest Barcelona<\/strong><\/h2>\n<p>Reservar el Hotel Continental Palacete como base para su visita al Oktoberfest Barcelona le ofrece lo mejor de ambos mundos. Situado en la Rambla de Catalu\u00f1a, el hotel es un monumento espa\u00f1ol protegido en el coraz\u00f3n del distrito de L&#8217;Eixample, cerca de muchos de los edificios m\u00e1s emblem\u00e1ticos de la capital catalana y de las zonas comerciales. Con habitaciones y suites c\u00f3modas y relajantes, un servicio atento y un buf\u00e9 24 horas, se encuentra en una ubicaci\u00f3n ideal para esas escapadas a la ciudad.<\/p>\n<p>Lo mejor de todo es que, desde el emblem\u00e1tico Hotel Continental Palacete, est\u00e1 a s\u00f3lo cinco minutos en taxi o a un agradable paseo de 25 minutos del recinto del Oktoberfest, pasando por muchas de las atracciones m\u00e1s famosas de Barcelona.<\/p>\n<p>Este a\u00f1o, \u00bfpor qu\u00e9 no combinar la Oktoberfest de Barcelona y un poco de turismo por la ciudad, con una estancia en el hermoso Hotel Continental Palacete?<\/p>","protected":false},"excerpt":{"rendered":"<p>Venga a disfrutar del Festival Oktoberfest Barcelona y qu\u00e9dese con nosotros!\u00a0 Si una visita a la Oktoberfest est\u00e1 en tu lista de deseos, pero las temperaturas de octubre en la fr\u00eda M\u00fanich te siguen retrasando, hay buenas noticias. El\u00a0Oktoberfest Barcelona\u00a0vuelve al recinto ferial de Montju\u00efc del 5 de octubre de 2022 al 16 de octubre [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":7845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1,15,196,840,3,4],"tags":[57,347,350,14,348],"class_list":["post-7843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona","category-culture","category-festivals","category-food-and-culture","category-hotel-continental","category-hotel-palacete","tag-agenda-barcelona","tag-barcelona","tag-culture","tag-festival","tag-hotel-continental"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hotel Palacete Barcelona Oktoberfest Barcelona festival<\/title>\n<meta name=\"description\" content=\"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel Palacete Barcelona Oktoberfest Barcelona festival\" \/>\n<meta property=\"og:description\" content=\"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Continental Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-09T15:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1135\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pili Malagarriga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pili Malagarriga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/\"},\"author\":{\"name\":\"Pili Malagarriga\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/#\\\/schema\\\/person\\\/12394e3da9d0dac0fd7f7600aa6930e3\"},\"headline\":\"La Oktoberfest Barcelona vuelve al recinto ferial de Montju\u00efc en 2022\",\"datePublished\":\"2022-09-09T15:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/\"},\"wordCount\":1046,\"image\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png\",\"keywords\":[\"Agenda Barcelona\",\"Barcelona\",\"Culture\",\"Festival\",\"Hotel Continental\"],\"articleSection\":[\"Barcelona\",\"Culture\",\"Festivals\",\"Food and culture\",\"Hotel Continental\",\"Hotel Palacete\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/\",\"url\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/\",\"name\":\"Hotel Palacete Barcelona Oktoberfest Barcelona festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png\",\"datePublished\":\"2022-09-09T15:23:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/#\\\/schema\\\/person\\\/12394e3da9d0dac0fd7f7600aa6930e3\"},\"description\":\"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png\",\"contentUrl\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png\",\"width\":1135,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/hotel-palacete-barcelona-oktoberfest-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oktoberfest Barcelona returns to the Montju\u00efc exhibition centre in 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/\",\"name\":\"Hotel Continental Barcelona\",\"description\":\"Dos hoteles emblem\u00e1ticos en el centro de Barcelona.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/#\\\/schema\\\/person\\\/12394e3da9d0dac0fd7f7600aa6930e3\",\"name\":\"Pili Malagarriga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g\",\"caption\":\"Pili Malagarriga\"},\"url\":\"https:\\\/\\\/blog.hotelcontinental.com\\\/es\\\/author\\\/pmv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel Palacete Barcelona Oktoberfest Barcelona festival","description":"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Hotel Palacete Barcelona Oktoberfest Barcelona festival","og_description":"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now","og_url":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/","og_site_name":"Hotel Continental Barcelona","article_published_time":"2022-09-09T15:23:58+00:00","og_image":[{"width":1135,"height":630,"url":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","type":"image\/png"}],"author":"Pili Malagarriga","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pili Malagarriga","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.hotelcontinental.com\/hotel-palacete-barcelona-oktoberfest-barcelona\/#article","isPartOf":{"@id":"https:\/\/blog.hotelcontinental.com\/hotel-palacete-barcelona-oktoberfest-barcelona\/"},"author":{"name":"Pili Malagarriga","@id":"https:\/\/blog.hotelcontinental.com\/#\/schema\/person\/12394e3da9d0dac0fd7f7600aa6930e3"},"headline":"La Oktoberfest Barcelona vuelve al recinto ferial de Montju\u00efc en 2022","datePublished":"2022-09-09T15:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.hotelcontinental.com\/hotel-palacete-barcelona-oktoberfest-barcelona\/"},"wordCount":1046,"image":{"@id":"https:\/\/blog.hotelcontinental.com\/hotel-palacete-barcelona-oktoberfest-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","keywords":["Agenda Barcelona","Barcelona","Culture","Festival","Hotel Continental"],"articleSection":["Barcelona","Culture","Festivals","Food and culture","Hotel Continental","Hotel Palacete"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/","url":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/","name":"Hotel Palacete Barcelona Oktoberfest Barcelona festival","isPartOf":{"@id":"https:\/\/blog.hotelcontinental.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/blog.hotelcontinental.com\/hotel-palacete-barcelona-oktoberfest-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","datePublished":"2022-09-09T15:23:58+00:00","author":{"@id":"https:\/\/blog.hotelcontinental.com\/#\/schema\/person\/12394e3da9d0dac0fd7f7600aa6930e3"},"description":"Hotel Palacete Barcelona | Oktoberfest Barcelona All Inclusive Hotel with a prime location on in Barcelona city center. Book now","breadcrumb":{"@id":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/#primaryimage","url":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","contentUrl":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","width":1135,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/blog.hotelcontinental.com\/es\/hotel-palacete-barcelona-oktoberfest-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.hotelcontinental.com\/es\/"},{"@type":"ListItem","position":2,"name":"Oktoberfest Barcelona returns to the Montju\u00efc exhibition centre in 2022"}]},{"@type":"WebSite","@id":"https:\/\/blog.hotelcontinental.com\/es\/#website","url":"https:\/\/blog.hotelcontinental.com\/es\/","name":"Hotel Continental Barcelona","description":"Dos hoteles emblem\u00e1ticos en el centro de Barcelona.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.hotelcontinental.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/blog.hotelcontinental.com\/#\/schema\/person\/12394e3da9d0dac0fd7f7600aa6930e3","name":"Pili Malagarriga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f3df02b57859c445040c0157e1de07a85925a9a196d927332aa63f4dbe5f01b?s=96&d=robohash&r=g","caption":"Pili Malagarriga"},"url":"https:\/\/blog.hotelcontinental.com\/es\/author\/pmv\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blog.hotelcontinental.com\/wp-content\/uploads\/2022\/09\/portada-Screen_Shot_2022-08-14_at_20.08_.46_.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8jyDf-22v","_links":{"self":[{"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/posts\/7843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/comments?post=7843"}],"version-history":[{"count":2,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/posts\/7843\/revisions"}],"predecessor-version":[{"id":7848,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/posts\/7843\/revisions\/7848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/media\/7845"}],"wp:attachment":[{"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/media?parent=7843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/categories?post=7843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.hotelcontinental.com\/es\/wp-json\/wp\/v2\/tags?post=7843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}